{"id":585,"date":"2020-10-09T10:21:10","date_gmt":"2020-10-09T08:21:10","guid":{"rendered":"http:\/\/conference.clinam.org\/?page_id=585"},"modified":"2023-09-12T10:41:38","modified_gmt":"2023-09-12T08:41:38","slug":"virtual-exhibition","status":"publish","type":"page","link":"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/","title":{"rendered":"Exhibitor&#8217;s 2023"},"content":{"rendered":"<p>[vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Exhibitor&#8217;s 2023&#8243; font_container=&#8221;tag:h2|text_align:left|color:%23ff0000&#8243; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221; css=&#8221;.vc_custom_1602746242911{border-radius: 5px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;651&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.lipoid.com\/en\/node\/15\" target=\"_blank\" rel=\"noopener noreferrer\">www.lipoid.com<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;640&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.polymun.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.polymun.com<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;631&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.innomedica.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.innomedica.com<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1417&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/ardena.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">ardena.com\/<\/a>[\/vc_hoverbox][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1052&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.precisionnanosystems.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">precisionnanosystems.com<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1057&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.phospholipid-research-center.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">phospholipid-research-center.com<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;660&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.clinam.org\" target=\"_blank\" rel=\"noopener noreferrer\">www.clinam.org<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1469&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/resistell.com\/\">resistell.com<\/a>[\/vc_hoverbox][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1408&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.nanofcm.com\/\">nanofcm.com<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1472&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.ciber-bbn.es\/en\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.izon.com\/ciber-bbn.es\/en<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;658&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/precisionnanomedicine.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.precisionnanomedicine.com<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1439&#8243; primary_title=&#8221;&#8221;]<a href=\"https:\/\/cordenpharma.com\/\">cordenpharma.com<\/a>[\/vc_hoverbox][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1475&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/syvento.com\/\">syvento.com\/<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1476&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.apv-mainz.de\/en\/pharma-verfahrenstechnik\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.apv-mainz.de\/<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1491&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.postnova.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">postnova.com<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1493&#8243; primary_title=&#8221;&#8221; hover_title=&#8221;&#8221;]<a href=\"https:\/\/nucleosyn.com\">nucleosyn.com<\/a>[\/vc_hoverbox][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1496&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/www.nanolyze.se\">nanolyze.se<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1498&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;][\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1499&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]<a href=\"https:\/\/clinam.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">clinam.org<\/a>[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Exhibitor&#8217;s 2023&#8243; font_container=&#8221;tag:h2|text_align:left|color:%23ff0000&#8243; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221; css=&#8221;.vc_custom_1602746242911{border-radius: 5px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;651&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.lipoid.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;640&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.polymun.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;631&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.innomedica.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1417&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]ardena.com\/[\/vc_hoverbox][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1052&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]precisionnanosystems.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1057&#8243;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-585","page","type-page","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exhibitor&#039;s 2023 - Conference Clinam 23<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exhibitor&#039;s 2023 - Conference Clinam 23\" \/>\n<meta property=\"og:description\" content=\"[vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Exhibitor&#8217;s 2023&#8243; font_container=&#8221;tag:h2|text_align:left|color:%23ff0000&#8243; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221; css=&#8221;.vc_custom_1602746242911{border-radius: 5px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;651&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.lipoid.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;640&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.polymun.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;631&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.innomedica.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1417&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]ardena.com\/[\/vc_hoverbox][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1052&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]precisionnanosystems.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1057&#8243;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/\" \/>\n<meta property=\"og:site_name\" content=\"Conference Clinam 23\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T08:41:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#organization\",\"name\":\"conference CLINAM 2022\",\"url\":\"https:\/\/conference.clinam23.clinam.org\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2020\/09\/logo-clinam-20.jpg\",\"contentUrl\":\"https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2020\/09\/logo-clinam-20.jpg\",\"width\":340,\"height\":79,\"caption\":\"conference CLINAM 2022\"},\"image\":{\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#website\",\"url\":\"https:\/\/conference.clinam23.clinam.org\/\",\"name\":\"Conference Clinam 23\",\"description\":\"CLINAM Summit Lounge\",\"publisher\":{\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conference.clinam23.clinam.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/#webpage\",\"url\":\"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/\",\"name\":\"Exhibitor's 2023 - Conference Clinam 23\",\"isPartOf\":{\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#website\"},\"datePublished\":\"2020-10-09T08:21:10+00:00\",\"dateModified\":\"2023-09-12T08:41:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/conference.clinam23.clinam.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exhibitor&#8217;s 2023\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exhibitor's 2023 - Conference Clinam 23","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/","og_locale":"en_US","og_type":"article","og_title":"Exhibitor's 2023 - Conference Clinam 23","og_description":"[vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Exhibitor&#8217;s 2023&#8243; font_container=&#8221;tag:h2|text_align:left|color:%23ff0000&#8243; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221; css=&#8221;.vc_custom_1602746242911{border-radius: 5px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;651&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.lipoid.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;640&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.polymun.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;631&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]www.innomedica.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1417&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]ardena.com\/[\/vc_hoverbox][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; content_placement=&#8221;top&#8221; css_animation=&#8221;zoomIn&#8221; el_class=&#8221;.exhibitionrow&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1052&#8243; primary_title=&#8221;&#8221; primary_align=&#8221;justify&#8221; hover_title=&#8221;&#8221; align=&#8221;left&#8221;]precisionnanosystems.com[\/vc_hoverbox][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_hoverbox image=&#8221;1057&#8243;&hellip;","og_url":"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/","og_site_name":"Conference Clinam 23","article_modified_time":"2023-09-12T08:41:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/conference.clinam23.clinam.org\/#organization","name":"conference CLINAM 2022","url":"https:\/\/conference.clinam23.clinam.org\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/conference.clinam23.clinam.org\/#logo","inLanguage":"en-US","url":"https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2020\/09\/logo-clinam-20.jpg","contentUrl":"https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2020\/09\/logo-clinam-20.jpg","width":340,"height":79,"caption":"conference CLINAM 2022"},"image":{"@id":"https:\/\/conference.clinam23.clinam.org\/#logo"}},{"@type":"WebSite","@id":"https:\/\/conference.clinam23.clinam.org\/#website","url":"https:\/\/conference.clinam23.clinam.org\/","name":"Conference Clinam 23","description":"CLINAM Summit Lounge","publisher":{"@id":"https:\/\/conference.clinam23.clinam.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conference.clinam23.clinam.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/#webpage","url":"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/","name":"Exhibitor's 2023 - Conference Clinam 23","isPartOf":{"@id":"https:\/\/conference.clinam23.clinam.org\/#website"},"datePublished":"2020-10-09T08:21:10+00:00","dateModified":"2023-09-12T08:41:38+00:00","breadcrumb":{"@id":"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/conference.clinam23.clinam.org\/index.php\/virtual-exhibition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/conference.clinam23.clinam.org\/"},{"@type":"ListItem","position":2,"name":"Exhibitor&#8217;s 2023"}]}]}},"_links":{"self":[{"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/pages\/585"}],"collection":[{"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/comments?post=585"}],"version-history":[{"count":88,"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/pages\/585\/revisions"}],"predecessor-version":[{"id":1466,"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/pages\/585\/revisions\/1466"}],"wp:attachment":[{"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/media?parent=585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}