{"id":171,"date":"2020-09-03T07:23:10","date_gmt":"2020-09-03T05:23:10","guid":{"rendered":"http:\/\/conference.clinam.org\/?page_id=171"},"modified":"2023-09-21T14:37:40","modified_gmt":"2023-09-21T12:37:40","slug":"proceedings-2","status":"publish","type":"page","link":"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/","title":{"rendered":"Proceedings"},"content":{"rendered":"<p>[vc_row gap=&#8221;35&#8243;][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Proceedings&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ff0000&#8243; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row full_height=&#8221;yes&#8221; columns_placement=&#8221;top&#8221;][vc_column css=&#8221;.vc_custom_1694511360249{background-color: #ff0000 !important;border-radius: 5px !important;}&#8221;][vc_wp_text]https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2023\/09\/DOWNLOAD-PROCEEDINGS-23-3.pdf[\/vc_wp_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row gap=&#8221;35&#8243;][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Proceedings&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ff0000&#8243; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:PT%20Sans%3Aregular%2Citalic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row full_height=&#8221;yes&#8221; columns_placement=&#8221;top&#8221;][vc_column css=&#8221;.vc_custom_1694511360249{background-color: #ff0000 !important;border-radius: 5px !important;}&#8221;][vc_wp_text]https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2023\/09\/DOWNLOAD-PROCEEDINGS-23-3.pdf[\/vc_wp_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-171","page","type-page","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Proceedings - Conference Clinam 23<\/title>\n<meta name=\"description\" content=\"From Hope to Product \u2013 The Brilliant Prospect in Nanomedicine and Related Fields\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proceedings - Conference Clinam 23\" \/>\n<meta property=\"og:description\" content=\"From Hope to Product \u2013 The Brilliant Prospect in Nanomedicine and Related Fields\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Conference Clinam 23\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-21T12:37:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#organization\",\"name\":\"conference CLINAM 2022\",\"url\":\"https:\/\/conference.clinam23.clinam.org\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2020\/09\/logo-clinam-20.jpg\",\"contentUrl\":\"https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2020\/09\/logo-clinam-20.jpg\",\"width\":340,\"height\":79,\"caption\":\"conference CLINAM 2022\"},\"image\":{\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#website\",\"url\":\"https:\/\/conference.clinam23.clinam.org\/\",\"name\":\"Conference Clinam 23\",\"description\":\"CLINAM Summit Lounge\",\"publisher\":{\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conference.clinam23.clinam.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/#webpage\",\"url\":\"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/\",\"name\":\"Proceedings - Conference Clinam 23\",\"isPartOf\":{\"@id\":\"https:\/\/conference.clinam23.clinam.org\/#website\"},\"datePublished\":\"2020-09-03T05:23:10+00:00\",\"dateModified\":\"2023-09-21T12:37:40+00:00\",\"description\":\"From Hope to Product \u2013 The Brilliant Prospect in Nanomedicine and Related Fields\",\"breadcrumb\":{\"@id\":\"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/conference.clinam23.clinam.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proceedings\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proceedings - Conference Clinam 23","description":"From Hope to Product \u2013 The Brilliant Prospect in Nanomedicine and Related Fields","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/","og_locale":"en_US","og_type":"article","og_title":"Proceedings - Conference Clinam 23","og_description":"From Hope to Product \u2013 The Brilliant Prospect in Nanomedicine and Related Fields","og_url":"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/","og_site_name":"Conference Clinam 23","article_modified_time":"2023-09-21T12:37:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/conference.clinam23.clinam.org\/#organization","name":"conference CLINAM 2022","url":"https:\/\/conference.clinam23.clinam.org\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/conference.clinam23.clinam.org\/#logo","inLanguage":"en-US","url":"https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2020\/09\/logo-clinam-20.jpg","contentUrl":"https:\/\/conference.clinam23.clinam.org\/wp-content\/uploads\/2020\/09\/logo-clinam-20.jpg","width":340,"height":79,"caption":"conference CLINAM 2022"},"image":{"@id":"https:\/\/conference.clinam23.clinam.org\/#logo"}},{"@type":"WebSite","@id":"https:\/\/conference.clinam23.clinam.org\/#website","url":"https:\/\/conference.clinam23.clinam.org\/","name":"Conference Clinam 23","description":"CLINAM Summit Lounge","publisher":{"@id":"https:\/\/conference.clinam23.clinam.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conference.clinam23.clinam.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/#webpage","url":"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/","name":"Proceedings - Conference Clinam 23","isPartOf":{"@id":"https:\/\/conference.clinam23.clinam.org\/#website"},"datePublished":"2020-09-03T05:23:10+00:00","dateModified":"2023-09-21T12:37:40+00:00","description":"From Hope to Product \u2013 The Brilliant Prospect in Nanomedicine and Related Fields","breadcrumb":{"@id":"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/conference.clinam23.clinam.org\/index.php\/proceedings-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/conference.clinam23.clinam.org\/"},{"@type":"ListItem","position":2,"name":"Proceedings"}]}]}},"_links":{"self":[{"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/pages\/171"}],"collection":[{"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":60,"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/pages\/171\/revisions"}],"predecessor-version":[{"id":1532,"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/pages\/171\/revisions\/1532"}],"wp:attachment":[{"href":"https:\/\/conference.clinam23.clinam.org\/index.php\/wp-json\/wp\/v2\/media?parent=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}